{"id":46048,"date":"2025-11-11T09:19:16","date_gmt":"2025-11-11T09:19:16","guid":{"rendered":"https:\/\/newelfinsvi.gbsweb.online\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/"},"modified":"2026-08-02T01:20:28","modified_gmt":"2026-08-02T01:20:28","slug":"doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18","status":"publish","type":"product","link":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/","title":{"rendered":"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[8233],"product_tag":[],"class_list":{"0":"post-46048","1":"product","2":"type-product","3":"status-publish","5":"product_cat-m4-serie","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin<\/title>\n<meta name=\"description\" content=\"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin\" \/>\n<meta property=\"og:description\" content=\"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/\" \/>\n<meta property=\"og:site_name\" content=\"New Elfin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-02T01:20:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/\",\"name\":\"040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin\",\"isPartOf\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#website\"},\"datePublished\":\"2025-11-11T09:19:16+00:00\",\"dateModified\":\"2026-08-02T01:20:28+00:00\",\"description\":\"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.\",\"breadcrumb\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Producten\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/producten\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#website\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/\",\"name\":\"New Elfin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#organization\"},\"alternateName\":\"New Elfin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#organization\",\"name\":\"New Elfin\",\"alternateName\":\"New Elfin\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"contentUrl\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"width\":696,\"height\":696,\"caption\":\"New Elfin\"},\"image\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/nl\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\",\"https:\/\/www.instagram.com\/newelfin\/\",\"https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin","description":"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/","og_locale":"nl_NL","og_type":"article","og_title":"040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin","og_description":"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.","og_url":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/","og_site_name":"New Elfin","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063680646472","article_modified_time":"2026-08-02T01:20:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/","url":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/","name":"040C2320-1P18 - Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - New Elfin","isPartOf":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#website"},"datePublished":"2025-11-11T09:19:16+00:00","dateModified":"2026-08-02T01:20:28+00:00","description":"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang - Cod: 040C2320-1P18. Technical data and product details on New Elfin.","breadcrumb":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/product\/doos-knoppenbord-aluminium-m4-230x205x100-18-gaten-o-22-zonder-kabelingang-040c2320-1p18\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newelfinsvi.gbsweb.online\/nl\/"},{"@type":"ListItem","position":2,"name":"Producten","item":"https:\/\/newelfinsvi.gbsweb.online\/nl\/producten\/"},{"@type":"ListItem","position":3,"name":"Doos knoppenbord aluminium M4 230x205x100, 18 gaten \u00d8 22, zonder kabelingang"}]},{"@type":"WebSite","@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#website","url":"https:\/\/newelfinsvi.gbsweb.online\/nl\/","name":"New Elfin","description":"","publisher":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#organization"},"alternateName":"New Elfin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newelfinsvi.gbsweb.online\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#organization","name":"New Elfin","alternateName":"New Elfin","url":"https:\/\/newelfinsvi.gbsweb.online\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","contentUrl":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","width":696,"height":696,"caption":"New Elfin"},"image":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063680646472","https:\/\/www.instagram.com\/newelfin\/","https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ"]}]}},"_links":{"self":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/product\/46048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/media?parent=46048"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/product_brand?post=46048"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/product_cat?post=46048"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/nl\/wp-json\/wp\/v2\/product_tag?post=46048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}