{"id":58746,"date":"2026-07-29T23:05:23","date_gmt":"2026-07-29T23:05:23","guid":{"rendered":"https:\/\/newelfinsvi.gbsweb.online\/product\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/"},"modified":"2026-08-02T00:10:23","modified_gmt":"2026-08-02T00:10:23","slug":"selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd","status":"publish","type":"product","link":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/","title":{"rendered":"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[7930],"product_tag":[],"class_list":{"0":"post-58746","1":"product","2":"type-product","3":"status-publish","5":"product_cat-selectores-d22","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin<\/title>\n<meta name=\"description\" content=\"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin\" \/>\n<meta property=\"og:description\" content=\"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/\" \/>\n<meta property=\"og:site_name\" content=\"New Elfin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-02T00:10:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/\",\"name\":\"020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin\",\"isPartOf\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#website\"},\"datePublished\":\"2026-07-29T23:05:23+00:00\",\"dateModified\":\"2026-08-02T00:10:23+00:00\",\"description\":\"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.\",\"breadcrumb\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Productos\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/productos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#website\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/\",\"name\":\"New Elfin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#organization\"},\"alternateName\":\"New Elfin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#organization\",\"name\":\"New Elfin\",\"alternateName\":\"New Elfin\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"contentUrl\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"width\":696,\"height\":696,\"caption\":\"New Elfin\"},\"image\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\",\"https:\/\/www.instagram.com\/newelfin\/\",\"https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin","description":"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/","og_locale":"es_ES","og_type":"article","og_title":"020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin","og_description":"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.","og_url":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/","og_site_name":"New Elfin","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063680646472","article_modified_time":"2026-08-02T00:10:23+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/","url":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/","name":"020STAMLABWD - Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - New Elfin","isPartOf":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#website"},"datePublished":"2026-07-29T23:05:23+00:00","dateModified":"2026-08-02T00:10:23+00:00","description":"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal - Cod: 020STAMLABWD. Technical data and product details on New Elfin.","breadcrumb":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/producto\/selector-luminoso-de-mando-blanco-2-posiciones-cam-a-muelle-con-retorno-desde-derecha-a-izquierda-metal-020stamlabwd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newelfinsvi.gbsweb.online\/es\/"},{"@type":"ListItem","position":2,"name":"Productos","item":"https:\/\/newelfinsvi.gbsweb.online\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"Selector luminoso de mando, blanco, 2 posiciones, Cam A, muelle con retorno desde derecha a izquierda, metal"}]},{"@type":"WebSite","@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#website","url":"https:\/\/newelfinsvi.gbsweb.online\/es\/","name":"New Elfin","description":"","publisher":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#organization"},"alternateName":"New Elfin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newelfinsvi.gbsweb.online\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#organization","name":"New Elfin","alternateName":"New Elfin","url":"https:\/\/newelfinsvi.gbsweb.online\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","contentUrl":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","width":696,"height":696,"caption":"New Elfin"},"image":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063680646472","https:\/\/www.instagram.com\/newelfin\/","https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ"]}]}},"_links":{"self":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/product\/58746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/media?parent=58746"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/product_brand?post=58746"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/product_cat?post=58746"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/es\/wp-json\/wp\/v2\/product_tag?post=58746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}