{"id":41620,"date":"2025-11-11T09:13:30","date_gmt":"2025-11-11T09:13:30","guid":{"rendered":"https:\/\/newelfinsvi.gbsweb.online\/product\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/"},"modified":"2026-08-02T00:05:16","modified_gmt":"2026-08-02T00:05:16","slug":"beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd","status":"publish","type":"product","link":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/","title":{"rendered":"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_brand":[],"product_cat":[8031],"product_tag":[],"class_list":{"0":"post-41620","1":"product","2":"type-product","3":"status-publish","5":"product_cat-wahler-d22","7":"first","8":"instock","9":"shipping-taxable","10":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin<\/title>\n<meta name=\"description\" content=\"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin\" \/>\n<meta property=\"og:description\" content=\"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/\" \/>\n<meta property=\"og:site_name\" content=\"New Elfin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-02T00:05:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/\",\"name\":\"020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin\",\"isPartOf\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#website\"},\"datePublished\":\"2025-11-11T09:13:30+00:00\",\"dateModified\":\"2026-08-02T00:05:16+00:00\",\"description\":\"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.\",\"breadcrumb\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/produkte\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#website\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/\",\"name\":\"New Elfin\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#organization\"},\"alternateName\":\"New Elfin\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#organization\",\"name\":\"New Elfin\",\"alternateName\":\"New Elfin\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"contentUrl\":\"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png\",\"width\":696,\"height\":696,\"caption\":\"New Elfin\"},\"image\":{\"@id\":\"https:\/\/newelfinsvi.gbsweb.online\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100063680646472\",\"https:\/\/www.instagram.com\/newelfin\/\",\"https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin","description":"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/","og_locale":"de_DE","og_type":"article","og_title":"020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin","og_description":"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.","og_url":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/","og_site_name":"New Elfin","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100063680646472","article_modified_time":"2026-08-02T00:05:16+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/","url":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/","name":"020SMTLOGD - Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - New Elfin","isPartOf":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#website"},"datePublished":"2025-11-11T09:13:30+00:00","dateModified":"2026-08-02T00:05:16+00:00","description":"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet - Cod: 020SMTLOGD. Technical data and product details on New Elfin.","breadcrumb":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkt\/beleuchteter-drehknopf-wahlschalter-gelb-3-positionen-cam-o-federrucklauf-von-rechts-beleuchtet-020smtlogd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newelfinsvi.gbsweb.online\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/newelfinsvi.gbsweb.online\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Beleuchteter Drehknopf-Wahlschalter, gelb, 3 Positionen, Cam O, Federr\u00fccklauf von rechts beleuchtet"}]},{"@type":"WebSite","@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#website","url":"https:\/\/newelfinsvi.gbsweb.online\/de\/","name":"New Elfin","description":"","publisher":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#organization"},"alternateName":"New Elfin","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newelfinsvi.gbsweb.online\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#organization","name":"New Elfin","alternateName":"New Elfin","url":"https:\/\/newelfinsvi.gbsweb.online\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#\/schema\/logo\/image\/","url":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","contentUrl":"https:\/\/newelfinsvi.gbsweb.online\/wp-content\/uploads\/2025\/11\/newelfin-organization-logo-696px.png","width":696,"height":696,"caption":"New Elfin"},"image":{"@id":"https:\/\/newelfinsvi.gbsweb.online\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063680646472","https:\/\/www.instagram.com\/newelfin\/","https:\/\/www.youtube.com\/channel\/UCturF9YDzaXOYhmGVvjQRVQ"]}]}},"_links":{"self":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/product\/41620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/media?parent=41620"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/product_brand?post=41620"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/product_cat?post=41620"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/newelfinsvi.gbsweb.online\/de\/wp-json\/wp\/v2\/product_tag?post=41620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}